{"id":4792,"date":"2022-02-17T09:29:50","date_gmt":"2022-02-17T09:29:50","guid":{"rendered":"https:\/\/riadtizwa.com\/quarto-2-grand-suite-2-fes\/"},"modified":"2022-04-20T17:03:42","modified_gmt":"2022-04-20T17:03:42","slug":"quarto-2-grand-suite-2-fes","status":"publish","type":"page","link":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/","title":{"rendered":"Quarto 2 (Grand Suite 2) &#8211; Fes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4792\" class=\"elementor elementor-4792 elementor-1011\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63b0b65d elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"63b0b65d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64920b2e\" data-id=\"64920b2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fef899c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fef899c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-492f781d\" data-id=\"492f781d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1f4b8b elementor-widget elementor-widget-heading\" data-id=\"e1f4b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto 2, Grand Suite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4761d7 elementor-widget elementor-widget-text-editor\" data-id=\"1a4761d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este grande quarto fica no primeiro andar com vista para o p\u00e1tio. Sua parede de tadelakt decorativa esconde uma \u00e1rea de vestir walk-in. O tradicional teto de madeira ergue-se 4 metros acima da sua cama de quatro cartazes. Suas janelas de vitrais lan\u00e7am uma bela luz sobre o quarto. Beneficia de uma casa de banho e de uma casa de banho separada. Os quartos disp\u00f5em de ar condicionado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b62c37 elementor-align-center elementor-widget elementor-widget-global elementor-global-5283 elementor-global-1435 elementor-widget-button\" data-id=\"8b62c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/direct-book.com\/properties\/riadtizwafesdirect\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserve este quarto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13ee47cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13ee47cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b419151\" data-id=\"1b419151\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e4527b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3e4527b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c010b4a\" data-id=\"4c010b4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e7d8a25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e7d8a25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45229bd3\" data-id=\"45229bd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f0f84e3 elementor-widget elementor-widget-heading\" data-id=\"5f0f84e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eleg\u00e2ncia e estilo. Camas confort\u00e1veis e len\u00e7\u00f3is luxuosos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-338d230f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"338d230f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5040ac61\" data-id=\"5040ac61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-716ba3f0 elementor-widget elementor-widget-image\" data-id=\"716ba3f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"672\" height=\"420\" src=\"https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.webp?fit=672%2C420&amp;ssl=1\" class=\"attachment-large size-large wp-image-4654\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21997d54 elementor-widget elementor-widget-heading\" data-id=\"21997d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Caracter\u00edsticas do quarto<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-725d00ec elementor-widget elementor-widget-text-editor\" data-id=\"725d00ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA cama \u00e9 super kingsize. Tamb\u00e9m vem com um grande sof\u00e1 que pode ser feito em uma cama de solteiro se h\u00e1 tr\u00eas de voc\u00eas que desejam ficar. A su\u00edte \u00e9 composta por uma banheira em tamanho real e um passeio no chuveiro e tem ar condicionado e aquecimento.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59596022 elementor-widget elementor-widget-text-editor\" data-id=\"59596022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cama Kingsize<\/p><p>Caminhada em tamanho real no chuveiro<\/p><p>Ar condicionado e aquecimento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4231c0b6\" data-id=\"4231c0b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63bac814 elementor-widget elementor-widget-image\" data-id=\"63bac814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"672\" height=\"420\" src=\"https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-fes-bedroom-2-view-MAIN-4.jpg?fit=672%2C420&amp;ssl=1\" class=\"attachment-large size-large wp-image-4656\" alt=\"riad tizwa Fes beautiful window\" srcset=\"https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-fes-bedroom-2-view-MAIN-4.jpg?w=672&amp;ssl=1 672w, https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-fes-bedroom-2-view-MAIN-4.jpg?resize=300%2C188&amp;ssl=1 300w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4986865b elementor-widget elementor-widget-heading\" data-id=\"4986865b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vista atrav\u00e9s da colunata<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8259d7 elementor-widget elementor-widget-text-editor\" data-id=\"e8259d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLocalizado no primeiro andar, tem uma bela vista sobre a colunata e para baixo para o p\u00e1tio por baixo de suas vitrais.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e65933c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4e65933c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad7e48f\" data-id=\"ad7e48f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6f94fa elementor-widget elementor-widget-heading\" data-id=\"7c6f94fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Outros quartos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c249dc2 elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"c249dc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-1-grand-suite-1-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Riad Tizwa marrakech Grand Suite 1\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Grand-Suite-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tGrand Suite 1\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Luxury Hotel Rooms for Rent\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Grand-Suite-2.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tGrand Suite 2\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-3-suite-1-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Traditional Moroccan Riad\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Suite-1-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tSuite 1\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-4-suite-2-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Suite 2\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Suite-2-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tSuite 2\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-5-grand-suite-3-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Double Bedroom for Rent in Fes, Morocco | Riad Tizwa Boutique Hotel\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Grand-Suite-3.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tRiad Tizwa marrakech Grand Suite 3\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-6-grande-duplo-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Large Double\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Large-Double-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tLarge Double\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-7-duplo-1-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Double 1\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Double-1-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tDouble 1\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-8-duplo-2-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Double 2\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Double-2-1.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tDouble 2\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-9-duplo-3-fes\/\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Riad Tizwa Boutique Hotel marrakech\" style=\"background-image: url(&#039;https:\/\/i0.wp.com\/riadtizwa.com\/wp-content\/uploads\/2022\/02\/Double-3.jpg?fit=860%2C536&amp;ssl=1&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-carousel-image-overlay e-overlay-animation-fade\">\n\t\t\t\tRiad Tizwa Boutique Hotel marrakech\t\t\t<\/div>\n\t\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e7dec7 elementor-widget elementor-widget-text-editor\" data-id=\"74e7dec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/riadtizwa.com\/pt-pt\/salas-fes\/\">Ver todos os nossos quartos<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quarto 2, Grand Suite Este grande quarto fica no primeiro andar com vista para o p\u00e1tio. Sua parede de tadelakt decorativa esconde uma \u00e1rea de vestir walk-in. O tradicional teto de madeira ergue-se 4 metros acima da sua cama de quatro cartazes. Suas janelas de vitrais lan\u00e7am uma bela luz sobre o quarto. Beneficia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"folder":[13],"class_list":["post-4792","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quarto 2 (Grand Suite 2) - Fes | Riad Tizwa<\/title>\n<meta name=\"description\" content=\"Uma grande su\u00edte em uma casa tradicional marroquina localizada no topo da medina. Funcion\u00e1rios na m\u00e3o 24hs por dia e na melhor \u00e1rea em Fes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quarto 2 (Grand Suite 2) - Fes | Riad Tizwa\" \/>\n<meta property=\"og:description\" content=\"Uma grande su\u00edte em uma casa tradicional marroquina localizada no topo da medina. Funcion\u00e1rios na m\u00e3o 24hs por dia e na melhor \u00e1rea em Fes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/\" \/>\n<meta property=\"og:site_name\" content=\"Riad Tizwa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T17:03:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quarto 2 (Grand Suite 2) - Fes | Riad Tizwa","description":"Uma grande su\u00edte em uma casa tradicional marroquina localizada no topo da medina. Funcion\u00e1rios na m\u00e3o 24hs por dia e na melhor \u00e1rea em Fes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/","og_locale":"pt_PT","og_type":"article","og_title":"Quarto 2 (Grand Suite 2) - Fes | Riad Tizwa","og_description":"Uma grande su\u00edte em uma casa tradicional marroquina localizada no topo da medina. Funcion\u00e1rios na m\u00e3o 24hs por dia e na melhor \u00e1rea em Fes.","og_url":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/","og_site_name":"Riad Tizwa","article_modified_time":"2022-04-20T17:03:42+00:00","og_image":[{"url":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/","url":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/","name":"Quarto 2 (Grand Suite 2) - Fes | Riad Tizwa","isPartOf":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/#primaryimage"},"image":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/#primaryimage"},"thumbnailUrl":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.jpg","datePublished":"2022-02-17T09:29:50+00:00","dateModified":"2022-04-20T17:03:42+00:00","description":"Uma grande su\u00edte em uma casa tradicional marroquina localizada no topo da medina. Funcion\u00e1rios na m\u00e3o 24hs por dia e na melhor \u00e1rea em Fes.","breadcrumb":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/#primaryimage","url":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.jpg","contentUrl":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2022\/03\/Riad-Tizwa-Fes-bathrobes.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/riadtizwa.com\/pt-pt\/quarto-2-grand-suite-2-fes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riadtizwa.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Quarto 2 (Grand Suite 2) &#8211; Fes"}]},{"@type":"WebSite","@id":"https:\/\/riadtizwa.com\/pt-pt\/#website","url":"https:\/\/riadtizwa.com\/pt-pt\/","name":"Riad Tizwa","description":"","publisher":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riadtizwa.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/riadtizwa.com\/pt-pt\/#organization","name":"Riad Tizwa","url":"https:\/\/riadtizwa.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/riadtizwa.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2021\/12\/Tizwa-logo.svg","contentUrl":"https:\/\/riadtizwa.com\/wp-content\/uploads\/2021\/12\/Tizwa-logo.svg","width":91,"height":68,"caption":"Riad Tizwa"},"image":{"@id":"https:\/\/riadtizwa.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/pages\/4792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=4792"}],"version-history":[{"count":5,"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/pages\/4792\/revisions"}],"predecessor-version":[{"id":6667,"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/pages\/4792\/revisions\/6667"}],"wp:attachment":[{"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=4792"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/riadtizwa.com\/pt-pt\/wp-json\/wp\/v2\/folder?post=4792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}